{"id":14981,"date":"2026-07-22T13:20:49","date_gmt":"2026-07-22T13:20:49","guid":{"rendered":"https:\/\/hemabo.nl\/?page_id=14981"},"modified":"2026-07-22T13:30:27","modified_gmt":"2026-07-22T13:30:27","slug":"conditions-generales-de-vente-et-de-livraison-de-hemabo-kunststoftechniek-b-v","status":"publish","type":"page","link":"https:\/\/hemabo.nl\/fr\/algemene-verkoop-en-leveringsvoorwaardenvan-hemabo-kunststoftechniek-b-v\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales de vente et de livraison de Hemabo Kunststoftechniek B.V."},"content":{"rendered":"<h2 class=\"wp-block-heading\">Article 1 \u2013 Applicabilit\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1.1<\/strong>&nbsp;Les conditions ci-dessous s&#x27;appliquent syst\u00e9matiquement \u00e0 toutes les relations juridiques dans le cadre desquelles Hemabo Kunststoftechniek B.V. (ci-apr\u00e8s d\u00e9nomm\u00e9e \u201c Hemabo \u201d) effectue des travaux et\/ou livre des marchandises. Les conditions g\u00e9n\u00e9rales font en tout \u00e9tat de cause partie int\u00e9grante de tous les contrats auxquels Hemabo est partie et s\u2019appliquent \u00e9galement lors des n\u00e9gociations (phase pr\u00e9contractuelle) auxquelles Hemabo participe et qui pr\u00e9c\u00e8dent une \u00e9ventuelle relation juridique ou un contrat. Les pr\u00e9sentes conditions g\u00e9n\u00e9rales s\u2019appliquent \u00e9galement aux collaborateurs de Hemabo et \u00e0 sa direction, si et dans la mesure o\u00f9 ceux-ci viendraient \u00e0 \u00eatre li\u00e9s par une relation juridique avec la partie adverse \u00e0 un moment quelconque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1.2<\/strong>&nbsp;Les conditions ci-dessous restent exclusivement applicables, m\u00eame si le papier \u00e0 en-t\u00eate, les factures et\/ou tout autre document \u00e9manant de l'autre partie font r\u00e9f\u00e9rence ou mentionnent que ses conditions g\u00e9n\u00e9rales ou celles de tiers s'appliqueraient. Sauf accord \u00e9crit contraire, l'applicabilit\u00e9 des conditions g\u00e9n\u00e9rales ou des clauses de l'autre partie ou de tiers est exclue. En cas de conflit entre les conditions ci-dessous et les dispositions du contrat, les dispositions du contrat pr\u00e9valent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1.3<\/strong>&nbsp;Les ajouts, modifications, accords ou dispositions compl\u00e9mentaires, ainsi que les clauses d\u00e9rogatoires au contrat ou aux pr\u00e9sentes conditions g\u00e9n\u00e9rales par lesquelles Hemabo contracte des obligations ou donne son accord, ne sont pas consid\u00e9r\u00e9s comme convenus entre les parties tant qu&#x27;ils n&#x27;ont pas \u00e9t\u00e9 confirm\u00e9s par \u00e9crit par Hemabo. Hemabo se r\u00e9serve \u00e0 tout moment le droit de ne pas faire usage des clauses figurant dans les pr\u00e9sentes conditions g\u00e9n\u00e9rales. Les d\u00e9rogations aux pr\u00e9sentes conditions sont toujours ponctuelles, sauf si elles ont \u00e9t\u00e9 confirm\u00e9es par \u00e9crit entre les parties. Les engagements verbaux pris par des collaborateurs de Hemabo n\u2019engagent pas Hemabo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1.4<\/strong>&nbsp;Si une ou plusieurs stipulations des pr\u00e9sentes conditions g\u00e9n\u00e9rales sont nulles ou annul\u00e9es \u00e0 quelque moment que ce soit, en tout ou en partie, le contrat et les pr\u00e9sentes conditions resteront par ailleurs en vigueur et la stipulation concern\u00e9e sera remplac\u00e9e, d'un commun accord, par une stipulation qui se rapproche autant que possible de la port\u00e9e de celle d'origine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1.5<\/strong>&nbsp;Les ambigu\u00eft\u00e9s concernant l'explication ou le contenu d'une ou plusieurs clauses de nos conditions g\u00e9n\u00e9rales doivent \u00eatre interpr.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Article 2 \u2013 Offres<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.1<\/strong>&nbsp;Toutes les offres, devis, listes de prix et autres documents similaires, quelle que soit leur d\u00e9nomination, \u00e9manant de Hemabo sont sans engagement, sauf s&#x27;ils mentionnent un d\u00e9lai d&#x27;acceptation. Si aucun d\u00e9lai n&#x27;est mentionn\u00e9, un d\u00e9lai de 20 jours calendaires s&#x27;applique. Ce d\u00e9lai peut \u00eatre prolong\u00e9 par Hemabo par le biais d&#x27;une notification \u00e9crite adress\u00e9e \u00e0 la partie adverse, pr\u00e9cisant \u00e9galement la dur\u00e9e de la prolongation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.2<\/strong>&nbsp;Si un devis contient une offre sans engagement et que cette offre est accept\u00e9e par la partie adverse, Hemabo se r\u00e9serve le droit de r\u00e9voquer l&#x27;offre dans un d\u00e9lai de 2 jours ouvrables \u00e0 compter de la r\u00e9ception de l&#x27;acceptation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.3<\/strong>&nbsp;Les prix pratiqu\u00e9s par Hemabo ainsi que les prix mentionn\u00e9s dans le devis \/ l&#x27;offre s&#x27;entendent hors TVA, frais et autres taxes publiques. Ces frais peuvent notamment \u2013 mais pas exclusivement \u2013 comprendre les frais de d\u00e9placement et de s\u00e9jour, frais de transport, frais d&#x27;exp\u00e9dition, frais d&#x27;emballage, frais administratifs, frais d&#x27;installation et de (d\u00e9)montage, frais de stockage, frais de surveillance, frais d&#x27;assurance, frais d&#x27;\u00e9tude, droits d&#x27;importation et d&#x27;exportation, frais de mesure et notes de frais des tiers auxquels il a fait appel. Hemabo est habilit\u00e9e \u00e0 facturer s\u00e9par\u00e9ment ces frais engag\u00e9s dans le cadre de l\u2019ex\u00e9cution du contrat. Si aucun prix n\u2019a (encore) \u00e9t\u00e9 convenu, les prix et tarifs pratiqu\u00e9s par Hemabo au moment de l\u2019ex\u00e9cution des travaux ou de la livraison seront factur\u00e9s \u00e0 la partie adverse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.4<\/strong>&nbsp;Si l&#x27;acceptation de la partie adverse s&#x27;\u00e9carte de l&#x27;offre de Hemabo figurant dans le devis ou la proposition, Hemabo n&#x27;est pas li\u00e9e par ce contrat, \u00e0 moins qu&#x27;elle ne d\u00e9clare vouloir \u00eatre li\u00e9e par celui-ci.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.5<\/strong>&nbsp;Les offres et devis doivent toujours \u00eatre accept\u00e9s dans leur int\u00e9gralit\u00e9. Sauf indication contraire de la part de Hemabo, l&#x27;acceptation d&#x27;une partie seulement de l&#x27;offre n&#x27;entra\u00eene pas la conclusion d&#x27;un contrat concernant cette partie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.6<\/strong>&nbsp;Le devis ou l&#x27;offre repose sur l&#x27;ex\u00e9cution des travaux dans des conditions normales et pendant les horaires de travail habituels pratiqu\u00e9s par Hemabo, ainsi que sur la fourniture des mat\u00e9riaux n\u00e9cessaires \u00e0 cet effet, sauf accord contraire express\u00e9ment convenu par \u00e9crit entre les parties.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.7<\/strong>&nbsp;Le devis ou l&#x27;offre est \u00e9tabli sur la base des informations fournies par la partie adverse et, le cas \u00e9ch\u00e9ant, des mesures effectu\u00e9es par Hemabo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.8<\/strong>&nbsp;Les illustrations et descriptions, ainsi que les dimensions et poids figurant dans les brochures et les devis, ne sont pas contraignants pour Hemabo. Les \u00e9chantillons, brochures, dessins, maquettes, indications de couleurs, dimensions, poids et autres descriptions pr\u00e9sent\u00e9s et\/ou fournis sont aussi pr\u00e9cis que possible, mais ne sont donn\u00e9s qu&#x27;\u00e0 titre indicatif. Aucun droit ne peut en \u00eatre tir\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.9<\/strong>&nbsp;Sauf indication contraire, Hemabo ne garantit pas l&#x27;ad\u00e9quation \u00e0 l&#x27;usage pr\u00e9vu. L&#x27;ad\u00e9quation des produits livr\u00e9s \u00e0 une application particuli\u00e8re rel\u00e8ve de la responsabilit\u00e9 du cocontractant. Hemabo ne saurait \u00eatre tenue responsable des erreurs et des divergences concernant les illustrations, les dessins et les indications de dimensions et de poids figurant dans les devis, les offres et\/ou les confirmations de commande, et n\u2019est pas tenue de verser une indemnisation au titre de tout pr\u00e9judice, quels qu\u2019ils soient et pour quelque motif que ce soit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.10<\/strong>&nbsp;La partie adverse a connaissance des \u00e9carts constat\u00e9s. En ce qui concerne les produits livr\u00e9s, la partie adverse accepte les tol\u00e9rances applicables. Les l\u00e9gers \u00e9carts, qui restent dans les limites des tol\u00e9rances, ne constituent pas un motif de rejet. Dans ce cas, Hemabo n&#x27;est pas responsable et n&#x27;est pas tenue de verser une indemnisation au titre de quelque pr\u00e9judice que ce soit, de quelque nature que ce soit et pour quelque motif que ce soit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.11<\/strong>&nbsp;Tous les documents fournis par Hemabo, ainsi que les copies qui en sont faites, notamment les dessins, les descriptions de produits et les cahiers des charges, restent la propri\u00e9t\u00e9 de Hemabo, ainsi que le droit de les utiliser, et doivent lui \u00eatre restitu\u00e9s \u00e0 la premi\u00e8re demande de Hemabo ; sans son autorisation \u00e9crite, ces documents ne peuvent \u00eatre ni copi\u00e9s ni mis \u00e0 la disposition de tiers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.12<\/strong>&nbsp;La partie adverse garantit \u00e0 tout moment \u00e0 Hemabo que l&#x27;utilisation des donn\u00e9es fournies par elle ou de toute autre mani\u00e8re ne la mettra pas en situation de violation des dispositions l\u00e9gales ou des droits prot\u00e9g\u00e9s de tiers. La partie adverse indemnise int\u00e9gralement Hemabo pour toutes les cons\u00e9quences directes ou indirectes des r\u00e9clamations qu&#x27;un tiers pourrait valablement faire valoir \u00e0 son encontre en raison d&#x27;une violation de la garantie mentionn\u00e9e dans le pr\u00e9sent paragraphe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.13<\/strong>&nbsp;Hemabo se r\u00e9serve express\u00e9ment le droit de modifier les prix, m\u00eame apr\u00e8s la conclusion du contrat. Hemabo est en droit de r\u00e9percuter sur la partie adverse toute augmentation des tarifs, des charges, des taxes, des salaires, des frais de transport, des prix des mat\u00e9riaux n\u00e9cessaires, des taux de change, etc., survenue apr\u00e8s la conclusion du contrat. \u00e0 la partie adverse. En outre, Hemabo est en droit d&#x27;indexer ses prix chaque ann\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.14<\/strong>&nbsp;Les offres ou devis ne s'appliquent pas automatiquement aux commandes ult\u00e9rieures.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Article 3 \u2013 Dur\u00e9e du contrat ; d\u00e9lais de livraison, ex\u00e9cution et modification du contrat<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.1<\/strong>&nbsp;Le contrat entre Hemabo et la partie adverse prend fin d\u00e8s son ex\u00e9cution. Hemabo ex\u00e9cutera le contrat au mieux de ses connaissances et de ses capacit\u00e9s, conform\u00e9ment aux r\u00e8gles de l&#x27;art. Hemabo d\u00e9termine les modalit\u00e9s d&#x27;ex\u00e9cution du contrat, sauf accord contraire express\u00e9ment convenu par \u00e9crit entre les parties.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.2<\/strong>&nbsp;Le contrat est conclu d\u00e8s lors que la direction de Hemabo ou un salari\u00e9 muni d&#x27;une procuration suffisante confirme la commande. Dans les cas o\u00f9 la commande n\u2019est pas confirm\u00e9e, le contrat est conclu par l\u2019ex\u00e9cution effective de la commande. Hemabo est en droit d\u2019exiger de la partie adverse qu\u2019elle fournisse une garantie suffisante pour l\u2019ex\u00e9cution de ses obligations. Si la partie adverse ne donne pas suite \u00e0 cette demande de Hemabo, Hemabo est en droit de suspendre l&#x27;ex\u00e9cution de ses obligations ou de r\u00e9silier le contrat sans mise en demeure.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.3<\/strong>&nbsp;Les d\u00e9lais convenus ou indiqu\u00e9s n&#x27;engagent pas Hemabo, mais sont purement indicatifs. En aucun cas, ces d\u00e9lais ne peuvent \u00eatre consid\u00e9r\u00e9s comme des d\u00e9lais imp\u00e9ratifs. En cas de d\u00e9passement d\u2019un d\u00e9lai, la partie adverse doit toujours mettre Hemabo en demeure par \u00e9crit. Un d\u00e9lai raisonnable doit alors \u00eatre accord\u00e9 \u00e0 Hemabo pour qu\u2019elle puisse encore ex\u00e9cuter le contrat. Le d\u00e9lai raisonnable est d\u00e9termin\u00e9 en fonction du temps dont Hemabo, ses fournisseurs ou les tiers auxquels Hemabo fait appel ont besoin pour rem\u00e9dier aux d\u00e9fauts ou livrer des produits de remplacement. Le d\u00e9passement de ce d\u00e9lai ne donne pas \u00e0 la partie adverse le droit de r\u00e9silier le contrat, de refuser le paiement ou de manquer de quelque mani\u00e8re que ce soit \u00e0 ses obligations. De m\u00eame, le d\u00e9passement des d\u00e9lais de livraison n\u2019oblige pas Hemabo \u00e0 verser des dommages-int\u00e9r\u00eats, de quelque nature que ce soit et pour quelque motif que ce soit. Si le d\u00e9but ou l\u2019ex\u00e9cution du contrat est retard\u00e9 par des facteurs dont la partie adverse est responsable, les dommages et frais qui en r\u00e9sultent pour Hemabo doivent \u00eatre indemnis\u00e9s par la partie adverse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.4<\/strong>&nbsp;Hemabo fournit ses prestations conform\u00e9ment au cahier des charges. Cela signifie que la partie adverse doit fournir les sp\u00e9cifications, la conception, les plans et les fichiers STEP (ou \u00e9quivalents). Les fichiers STEP ou \u00e9quivalents font foi et sont d\u00e9terminants. La partie adverse est tenue de communiquer \u00e0 Hemabo, aux fins de l\u2019ex\u00e9cution du contrat, toutes les informations n\u00e9cessaires dont elle a connaissance ou dont elle peut raisonnablement savoir qu\u2019elles sont ou pourraient \u00eatre importantes pour l\u2019ex\u00e9cution de la commande. La partie adverse garantit l\u2019exactitude et l\u2019exhaustivit\u00e9 de ces informations. Le d\u00e9lai d\u2019ex\u00e9cution de cette commande ne commence \u00e0 courir qu\u2019apr\u00e8s que la partie adverse a mis ces informations \u00e0 la disposition de Hemabo. Hemabo n\u2019est pas responsable et n\u2019est pas tenue \u00e0 une indemnisation pour tout pr\u00e9judice, de quelque nature que ce soit et pour quelque motif que ce soit, r\u00e9sultant du fait que Hemabo s\u2019est fond\u00e9 sur des donn\u00e9es et sp\u00e9cifications inexactes et\/ou incompl\u00e8tes fournies par la partie adverse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.5<\/strong>&nbsp;Toutes les livraisons sont effectu\u00e9es sous r\u00e9serve de propri\u00e9t\u00e9, telle que d\u00e9crite \u00e0 l'article 6. La livraison s'entend du fait de placer les marchandises \u00e0 la disposition de la partie adverse ou d'un tiers d\u00e9sign\u00e9 qui vient chercher les marchandises sur instruction de la partie adverse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.6<\/strong>&nbsp;La partie adverse est tenue de contr\u00f4ler la livraison imm\u00e9diatement apr\u00e8s sa r\u00e9ception quant \u00e0 la quantit\u00e9, la qualit\u00e9, les sp\u00e9cifications et toute autre d\u00e9rogation \u00e0 ce qui a \u00e9t\u00e9 convenu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.7<\/strong>&nbsp;La livraison s&#x27;effectue d\u00e9part entrep\u00f4t Hemabo, sauf accord \u00e9crit contraire, soit par mise \u00e0 disposition de la partie adverse, soit par remise au transporteur concern\u00e9. L&#x27;exp\u00e9dition des marchandises s&#x27;effectue aux risques et aux frais de la partie adverse par un transporteur d\u00e9sign\u00e9 par Hemabo. La partie adverse est en droit de d\u00e9signer elle-m\u00eame un transporteur, \u00e0 ses frais et \u00e0 ses risques. La partie adverse est tenue de r\u00e9ceptionner les marchandises d\u00e8s qu\u2019elles sont mises \u00e0 sa disposition. Si la partie adverse refuse la r\u00e9ception ou n\u00e9glige de fournir les informations ou instructions n\u00e9cessaires \u00e0 la livraison, Hemabo est en droit de stocker les marchandises aux frais et aux risques de la partie adverse. Tous les dommages qui en d\u00e9coulent, y compris les dommages r\u00e9sultant de la non-r\u00e9ception des marchandises, sont \u00e0 la charge de la partie adverse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.8<\/strong>&nbsp;Toutes les marchandises livr\u00e9es \u00e0 la partie adverse sont aux risques et p\u00e9rils de la partie adverse \u00e0 compter de leur livraison. Il en va de m\u00eame \u00e0 partir du moment o\u00f9 la partie adverse est en d\u00e9faut d'accomplir les actes auxquels elle doit coop\u00e9rer pour la livraison.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.9<\/strong>&nbsp;Hemabo se r\u00e9serve le droit, pour des raisons techniques li\u00e9es \u00e0 la production ou en raison de l&#x27;unit\u00e9 d&#x27;emballage d&#x27;un article concern\u00e9, d&#x27;augmenter ou de r\u00e9duire la quantit\u00e9 pr\u00e9vue dans le contrat de 10% au maximum, sans en informer la partie adverse. La partie adverse est tenue de r\u00e9gler \u00e0 Hemabo le prix correspondant \u00e0 la quantit\u00e9 livr\u00e9e telle que modifi\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.10<\/strong>&nbsp;Hemabo est toujours habilit\u00e9e \u00e0 faire appel \u00e0 des tiers pour l&#x27;ex\u00e9cution de toute obligation d\u00e9coulant du contrat. Hemabo est en droit d&#x27;ex\u00e9cuter la commande en plusieurs phases, ou de livrer la commande par lots, et de facturer ces phases ou ces lots s\u00e9par\u00e9ment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.11<\/strong>&nbsp;Si la partie adverse s&#x27;est r\u00e9serv\u00e9 l&#x27;ex\u00e9cution de certaines parties du contrat, elle est responsable de tout retard dans la livraison ou dans l&#x27;ex\u00e9cution de celles-ci. La partie adverse doit veiller \u00e0 ce que les travaux \u00e0 r\u00e9aliser par des tiers, qui ne rel\u00e8vent pas du contrat conclu avec Hemabo, soient effectu\u00e9s de mani\u00e8re ad\u00e9quate et en temps utile, afin que l&#x27;ex\u00e9cution des travaux par Hemabo n&#x27;en subisse aucun retard.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.12<\/strong>&nbsp;Hemabo est toujours en droit, si le contrat est ex\u00e9cut\u00e9 par \u00e9tapes, de suspendre l&#x27;ex\u00e9cution des travaux relevant d&#x27;une \u00e9tape suivante jusqu&#x27;\u00e0 ce que la partie adverse ait approuv\u00e9 les travaux de l&#x27;\u00e9tape pr\u00e9c\u00e9dente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.13<\/strong>&nbsp;Si la partie adverse manque \u00e0 ses obligations vis\u00e9es au pr\u00e9sent article 3, Hemabo est en droit de suspendre ses activit\u00e9s, ou de r\u00e9silier le contrat sans mise en demeure pr\u00e9alable, sans \u00eatre tenue de lui verser une indemnit\u00e9 pour le pr\u00e9judice que cela pourrait causer \u00e0 la partie adverse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.14<\/strong>&nbsp;La partie adverse veille \u00e0 ce que toutes les donn\u00e9es et autorisations que Hemabo indique comme \u00e9tant n\u00e9cessaires, ou dont la partie adverse doit raisonnablement comprendre qu\u2019elles sont n\u00e9cessaires \u00e0 l\u2019ex\u00e9cution du contrat, soient fournies en temps utile \u00e0 Hemabo. Si les donn\u00e9es et autorisations n\u00e9cessaires \u00e0 l&#x27;ex\u00e9cution du contrat ne sont pas fournies en temps utile au producteur, Hemabo est en droit de facturer \u00e0 la partie adverse les frais suppl\u00e9mentaires r\u00e9sultant de ce retard, selon les tarifs habituels.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.15<\/strong>&nbsp;La partie adverse s&#x27;engage \u00e0 ne pas utiliser les r\u00e9sultats issus du contrat d&#x27;une mani\u00e8re qui enfreigne la l\u00e9gislation et la r\u00e9glementation en mati\u00e8re d&#x27;exportation. La partie adverse garantit Hemabo contre toute r\u00e9clamation de tiers fond\u00e9e sur le non-respect de la l\u00e9gislation et de la r\u00e9glementation en mati\u00e8re d&#x27;exportation. Hemabo peut proc\u00e9der \u00e0 la suspension de ses obligations et \u00e0 la suspension des droits de la partie adverse jusqu\u2019\u00e0 ce qu\u2019une autorisation requise par la l\u00e9gislation et la r\u00e9glementation en mati\u00e8re d\u2019exportation ait \u00e9t\u00e9 accord\u00e9e. Hemabo peut r\u00e9silier le contrat sans aucune obligation envers la partie adverse si cette autorisation n\u2019est pas accord\u00e9e ou si son octroi n\u2019est pas pr\u00e9visible dans un d\u00e9lai raisonnable. Hemabo peut en outre r\u00e9silier le contrat de mani\u00e8re anticip\u00e9e et avec effet imm\u00e9diat, sans \u00eatre tenue \u00e0 aucune indemnit\u00e9 envers la partie adverse, si la poursuite du contrat n\u2019est pas autoris\u00e9e en vertu de la l\u00e9gislation et de la r\u00e9glementation en mati\u00e8re d\u2019exportation.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Article 4 \u2013 Suspension, r\u00e9siliation et rupture anticip\u00e9e du contrat<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4.1<\/strong>&nbsp;Hemabo est toujours en droit de suspendre l&#x27;ex\u00e9cution de ses obligations ou de r\u00e9silier le contrat sans mise en demeure si :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">a. la partie adverse ne remplit pas ses obligations d\u00e9coulant du contrat, pas enti\u00e8rement ou pas en temps voulu ;<br>b. la partie adverse est liquid\u00e9e, demande un sursis de paiement ou une faillite, des saisies sont effectu\u00e9es au d\u00e9triment de la partie adverse, la partie adverse d\u00e9pose une demande d'application de la loi sur l'assainissement de la dette, ou toute autre circonstance emp\u00eachant la partie adverse de disposer librement de ses biens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4.2<\/strong>&nbsp;En cas de r\u00e9siliation du contrat, les cr\u00e9ances de Hemabo \u00e0 l&#x27;\u00e9gard de la partie adverse deviennent imm\u00e9diatement exigibles. Si Hemabo suspend l&#x27;ex\u00e9cution de ses obligations, elle conserve les droits qui lui reviennent en vertu de la loi et du contrat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4.3<\/strong>&nbsp;Si Hemabo proc\u00e8de \u00e0 la suspension ou \u00e0 la r\u00e9siliation du contrat, elle n&#x27;est en aucun cas tenue d&#x27;indemniser la partie adverse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4.4<\/strong>&nbsp;En cas de liquidation, de (demande de) sursis de paiement ou de faillite, de saisie \u2013 si et dans la mesure o\u00f9 la saisie n\u2019a pas \u00e9t\u00e9 lev\u00e9e dans un d\u00e9lai d\u2019un mois \u2013 \u00e0 la charge de la partie adverse, de r\u00e9\u00e9chelonnement de la dette ou de toute autre circonstance emp\u00eachant la partie adverse de disposer librement de son patrimoine, Hemabo est libre de r\u00e9silier le contrat imm\u00e9diatement et avec effet imm\u00e9diat ou d\u2019annuler la commande ou le contrat, sans aucune obligation de sa part de verser une quelconque indemnit\u00e9 ou compensation. Dans ce cas, les cr\u00e9ances de Hemabo \u00e0 l\u2019\u00e9gard de la partie adverse sont imm\u00e9diatement exigibles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Article 5 \u2013 Annulation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5.1<\/strong>&nbsp;Si la partie adverse annule, elle est tenue de verser des dommages-int\u00e9r\u00eats. Ceux-ci sont calcul\u00e9s sur la base du manque \u00e0 gagner, en fonction des moyennes du secteur. L&#x27;indemnit\u00e9 est calcul\u00e9e \u00e0 partir de la marge brute (co\u00fbts fixes et variables, marge b\u00e9n\u00e9ficiaire), d\u00e9duction faite des co\u00fbts variables non engag\u00e9s, tels que les frais de livraison. L&#x27;indemnit\u00e9 s&#x27;\u00e9l\u00e8ve \u00e0 30% du montant de la commande hors TVA, sauf accord contraire entre les parties. Elle s&#x27;\u00e9l\u00e8ve \u00e0 50% si la partie adverse annule alors qu&#x27;elle a d\u00e9j\u00e0 \u00e9t\u00e9 inform\u00e9e que la livraison (partielle) pouvait avoir lieu. En cas de travail sur mesure, le pourcentage est de 100%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5.2<\/strong>&nbsp;Les pourcentages mentionn\u00e9s au paragraphe 1 sont fixes, sauf si Hemabo peut prouver que son pr\u00e9judice est plus important ou si la partie adverse peut d\u00e9montrer de mani\u00e8re plausible que le pr\u00e9judice est moins important.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5.3<\/strong>&nbsp;Toute annulation doit de pr\u00e9f\u00e9rence \u00eatre effectu\u00e9e par \u00e9crit. En cas d&#x27;annulation verbale, Hemabo en donnera confirmation par \u00e9crit.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Article 6 \u2013 R\u00e9serve de propri\u00e9t\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6.1<\/strong>&nbsp;Toutes les marchandises livr\u00e9es et \u00e0 livrer restent la propri\u00e9t\u00e9 exclusive de Hemabo, jusqu\u2019au paiement int\u00e9gral de toutes les cr\u00e9ances que Hemabo d\u00e9tient ou d\u00e9tiendra \u00e0 l\u2019encontre de la partie adverse, y compris, en tout \u00e9tat de cause, les cr\u00e9ances vis\u00e9es \u00e0 l\u2019article 3:92, paragraphe 2, du Code civil n\u00e9erlandais, ainsi que les int\u00e9r\u00eats et les frais extrajudiciaires et judiciaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6.2<\/strong>&nbsp;La partie adverse n&#x27;est pas autoris\u00e9e \u00e0 revendre les marchandises livr\u00e9es ou \u00e0 livrer par Hemabo qui sont soumises \u00e0 la r\u00e9serve de propri\u00e9t\u00e9 de Hemabo. La partie adverse n&#x27;est en aucun cas autoris\u00e9e \u00e0 utiliser comme moyen de paiement les marchandises livr\u00e9es ou \u00e0 livrer qui sont soumises \u00e0 la r\u00e9serve de propri\u00e9t\u00e9 de Hemabo. La partie adverse n&#x27;est pas autoris\u00e9e \u00e0 mettre en gage ou \u00e0 grever de quelque mani\u00e8re que ce soit les marchandises soumises \u00e0 la r\u00e9serve de propri\u00e9t\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6.3<\/strong>&nbsp;La partie adverse mettra tout en \u0153uvre pour garantir les droits de propri\u00e9t\u00e9 de Hemabo sur les marchandises livr\u00e9es sous r\u00e9serve de propri\u00e9t\u00e9. Si des tiers proc\u00e8dent \u00e0 une saisie des marchandises livr\u00e9es sous r\u00e9serve de propri\u00e9t\u00e9 ou souhaitent \u00e9tablir ou faire valoir des droits (limit\u00e9s) sur celles-ci, la partie adverse est tenue d&#x27;en informer imm\u00e9diatement Hemabo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6.4<\/strong>&nbsp;La partie adverse s&#x27;engage \u00e0 assurer et \u00e0 maintenir assur\u00e9es les marchandises livr\u00e9es sous r\u00e9serve de propri\u00e9t\u00e9 contre l&#x27;incendie, les explosions, les d\u00e9g\u00e2ts des eaux ainsi que contre le vol, et \u00e0 mettre la police d&#x27;assurance \u00e0 la disposition de Hemabo pour consultation \u00e0 la premi\u00e8re demande. En cas de versement \u00e9ventuel de l&#x27;indemnit\u00e9 d&#x27;assurance, Hemabo a droit \u00e0 ces indemnit\u00e9s. La partie adverse accorde par la pr\u00e9sente un gage tacite \u00e0 Hemabo sur ces indemnit\u00e9s d\u2019assurance. Hemabo est habilit\u00e9e \u00e0 faire enregistrer le gage au nom de la partie adverse aupr\u00e8s du service des successions et de l\u2019enregistrement de l\u2019administration fiscale. En outre, Hemabo est habilit\u00e9e \u00e0 rendre public ce droit de gage \u00e0 tout moment de son choix.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6.5<\/strong>&nbsp;Au cas o\u00f9 Hemabo souhaiterait faire valoir ses droits de propri\u00e9t\u00e9, la partie adverse accorde d\u00e8s \u00e0 pr\u00e9sent \u00e0 Hemabo, ou \u00e0 des tiers d\u00e9sign\u00e9s par Hemabo, l\u2019autorisation inconditionnelle et irr\u00e9vocable d\u2019acc\u00e9der \u00e0 tous les locaux et lieux o\u00f9 se trouvent les biens de Hemabo et de r\u00e9cup\u00e9rer ces biens. Si la partie adverse manque \u00e0 cette obligation, elle est redevable d\u2019une p\u00e9nalit\u00e9 \u00e9gale \u00e0 15% de la valeur des biens qu\u2019elle d\u00e9tient alors ind\u00fbment. Hemabo est en droit de faire valoir ses droits de propri\u00e9t\u00e9 lorsque la partie adverse ne respecte pas ses obligations ou ne les respecte pas dans les d\u00e9lais impartis, ou s\u2019il existe une crainte fond\u00e9e qu\u2019elle ne le fasse pas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Article 7 \u2013 Paiement<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7.1<\/strong>&nbsp;Le paiement s'effectue comme suit, sauf accord \u00e9crit contraire entre les parties :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 30% du montant de la commande, TVA comprise, \u00e0 la conclusion du contrat ;<br>\u2013 70% du montant de la commande, TVA comprise, \u00e0 la livraison du ou des biens \u00e0 la partie adverse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7.2<\/strong>&nbsp;Nonobstant les dispositions du paragraphe 1, Hemabo est en droit d&#x27;exiger un paiement au comptant, ou d&#x27;exiger une partie du montant convenu \u00e0 titre d&#x27;acompte, ou encore d&#x27;obtenir de la partie adverse une autre garantie de paiement avant que celle-ci ne re\u00e7oive la livraison, le tout \u00e0 la discr\u00e9tion de Hemabo. Les montants \u00e9ventuellement restants doivent \u00eatre en possession de Hemabo avant l\u2019expiration du d\u00e9lai de paiement. Si Hemabo estime avoir des raisons d\u2019exiger le paiement du montant restant avant l\u2019expiration du d\u00e9lai de paiement officiel, la partie adverse est tenue de s\u2019y conformer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7.3<\/strong>&nbsp;Le d\u00e9lai de paiement est de 14 jours calendaires, sauf si un d\u00e9lai de paiement diff\u00e9rent est indiqu\u00e9 sur le devis\/la facture. Apr\u00e8s l'expiration du d\u00e9lai, la facture est consid\u00e9r\u00e9e comme irr\u00e9vocablement et inconditionnellement accept\u00e9e par l'autre partie. Les actions en justice \u00e9ventuelles doivent \u00eatre intent\u00e9es au plus tard un an apr\u00e8s une notification de r\u00e9clamation en temps voulu, sous peine de d\u00e9ch\u00e9ance. Les r\u00e9clamations \u00e9ventuelles ne suspendent pas l'obligation de paiement de l'autre partie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7.4<\/strong>&nbsp;En cas de non-respect, de respect tardif et\/ou de respect incomplet des dispositions des paragraphes susmentionn\u00e9s, la partie adverse est en d\u00e9faut, sans qu&#x27;une mise en demeure soit n\u00e9cessaire. En cas de d\u00e9faillance, ainsi qu\u2019en cas de demande de sursis de paiement, de faillite ou de liquidation de l\u2019entreprise de la partie adverse, celle-ci est redevable \u00e0 Hemabo d\u2019un int\u00e9r\u00eat de 1,5% par mois ; si ce taux est sup\u00e9rieur, la partie adverse est redevable \u00e0 Hemabo de l\u2019int\u00e9r\u00eat l\u00e9gal (commercial) pr\u00e9vu \u00e0 l\u2019article 6:119a du Code civil n\u00e9erlandais. Dans ce cas, Hemabo est \u00e9galement en droit de r\u00e9silier, sans aucune intervention judiciaire, tout ou partie des contrats en cours avec la partie adverse. La partie adverse est tenue d\u2019indemniser Hemabo de tous les frais et pr\u00e9judices qui en d\u00e9coulent pour Hemabo. En outre, tout cr\u00e9dit accord\u00e9 est alors annul\u00e9 et toutes les sommes dues au titre des autres relations juridiques (par exemple, des contrats) deviennent imm\u00e9diatement exigibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7.5<\/strong>&nbsp;En cas de d\u00e9faut de paiement, ainsi que dans les autres circonstances vis\u00e9es au paragraphe 3, tous les frais extrajudiciaires \u2013 y compris, en tout \u00e9tat de cause, tous les honoraires du mandataire \/ avocat mandat\u00e9, les frais de justice, notamment les droits de greffe, li\u00e9s \u00e0 la d\u00e9termination du pr\u00e9judice et de la responsabilit\u00e9, pour obtenir le paiement, ainsi que pour pr\u00e9venir ou limiter le pr\u00e9judice r\u00e9sultant des \u00e9v\u00e9nements sur lesquels repose la responsabilit\u00e9, les int\u00e9r\u00eats sur le principal et les autres frais \u2013 deviennent imm\u00e9diatement exigibles en plus du principal. Les frais extrajudiciaires correspondent en tout \u00e9tat de cause aux frais r\u00e9els factur\u00e9s \u00e0 Hemabo au titre de l\u2019assistance juridique, ou s\u2019\u00e9l\u00e8vent \u00e0 15% du montant principal, avec un minimum de 500 \u20ac,, major\u00e9s des frais engag\u00e9s et des taxes dues.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7.6<\/strong>&nbsp;Si Hemabo d\u00e9pose une demande de mise en faillite \u00e0 l&#x27;encontre de la partie adverse, celle-ci est redevable, outre le principal, les int\u00e9r\u00eats et les frais de recouvrement extrajudiciaires, des frais li\u00e9s \u00e0 la demande de mise en faillite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7.7<\/strong>&nbsp;Si, dans le cadre d&#x27;une proc\u00e9dure judiciaire, Hemabo obtient gain de cause en tout ou en partie, tous les frais engag\u00e9s par Hemabo dans le cadre de cette proc\u00e9dure seront \u00e0 la charge de la partie adverse, nonobstant une \u00e9ventuelle condamnation partielle aux d\u00e9pens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7.8<\/strong>&nbsp;Les paiements \u00e0 effectuer par le cocontractant devront \u00eatre faits nets, sans d\u00e9duction, suspension, compensation, novation, cession, d\u00e9charge ou toute autre cause que ce soit. Le cocontractant renonce donc express\u00e9ment \u00e0 ces droits.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Article 8 \u2013 Force majeure<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>8.1<\/strong>&nbsp;Si l&#x27;ex\u00e9cution du contrat est rendue impossible par une cause qui ne peut \u00eatre imput\u00e9e \u00e0 Hemabo et qui ne rel\u00e8ve pas non plus de sa sph\u00e8re de risque, Hemabo est en droit de mettre fin \u00e0 l&#x27;ex\u00e9cution du contrat et de facturer les frais engag\u00e9s \u00e0 la partie adverse. En tout cas de force majeure, Hemabo est en droit de r\u00e9silier tout ou partie du contrat pour la partie non ex\u00e9cut\u00e9e ou de suspendre l&#x27;ex\u00e9cution pendant la dur\u00e9e de la force majeure. Sont notamment consid\u00e9r\u00e9s comme des cas de force majeure : les incendies, les gr\u00e8ves, les lock-out, le sabotage, les \u00e9meutes, les troubles civils, la mobilisation, la guerre, la menace de guerre, l\u2019\u00e9tat de guerre, l\u2019\u00e9tat de si\u00e8ge, congestion, blocage du trafic terrestre, maritime ou a\u00e9rien, inondation, formation de glace et tout autre retard des moyens de transport, mesure prise par les pouvoirs publics, quels qu\u2019en soient le motif, la cause ou l\u2019impact, les cons\u00e9quences d\u2019une pand\u00e9mie ou d\u2019une \u00e9pid\u00e9mie, force majeure \u00e9conomique et obligations impos\u00e9es par la CE, hausse excessive des prix de l\u2019\u00e9nergie et des mati\u00e8res premi\u00e8res, coupure d\u2019\u00e9lectricit\u00e9, dysfonctionnement d\u2019un r\u00e9seau de communication, y compris Internet et autres moyens de communication ou \u00e9quipements d\u2019exploitation (ordinateurs, etc.), la faillite ou la suspension de paiement des prestataires de Hemabo dont elle d\u00e9pend pour l\u2019ex\u00e9cution du contrat, ainsi que le manquement total ou partiel de tiers dont Hemabo re\u00e7oit des biens ou des services, sans que Hemabo soit tenue de d\u00e9montrer l\u2019influence de ces \u00e9v\u00e9nements sur l\u2019emp\u00eachement ou le retard.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>8.2<\/strong>&nbsp;Le cas de force majeure s&#x27;applique \u00e9galement lorsque Hemabo commande les marchandises \u00e0 livrer aupr\u00e8s d&#x27;un tiers et que ce dernier, pour quelque raison que ce soit, manque \u00e0 son obligation de livraison. Lorsque des marchandises sont pr\u00eates mais ne peuvent \u00eatre achemin\u00e9es vers leur lieu de destination pour une cause ind\u00e9pendante de la volont\u00e9 de Hemabo, Hemabo est en droit de les entreposer aux frais et aux risques de la partie adverse et d&#x27;exiger leur paiement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>8.3<\/strong>&nbsp;En cas de force majeure, les obligations de Hemabo d\u00e9coulant du contrat sont suspendues pour la dur\u00e9e de cette force majeure, sans que Hemabo ne soit tenue \u00e0 aucune indemnisation \u00e0 ce titre. Les obligations de paiement d&#x27;une somme d&#x27;argent \u00e0 Hemabo ne peuvent en aucun cas \u00eatre suspendues par la partie adverse pour cause de force majeure.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Article 9 \u2013 Garanties, v\u00e9rifications et r\u00e9clamations, r\u00e9duction des d\u00e9lais de prescription et de forclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9.1<\/strong>&nbsp;Les marchandises vendues par Hemabo ne pr\u00e9sentent que les caract\u00e9ristiques n\u00e9cessaires \u00e0 leur utilisation normale. Hemabo a rempli son obligation de livrer des marchandises conformes au contrat si celles-ci r\u00e9pondent aux sp\u00e9cifications indiqu\u00e9es par la partie adverse et mentionn\u00e9es dans le contrat. Si la commande porte sur la transformation de marchandises fournies par la partie adverse, Hemabo garantit uniquement qu\u2019elle ex\u00e9cutera les travaux avec soin. Hemabo ne garantit pas l\u2019exactitude des donn\u00e9es, des plans et des mat\u00e9riaux fournis par la partie adverse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9.2<\/strong>&nbsp;Tous les conseils prodigu\u00e9s par Hemabo sont donn\u00e9s sans engagement, au mieux de ses connaissances et de ses capacit\u00e9s, et n&#x27;engagent en aucun cas sa responsabilit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9.3<\/strong>&nbsp;Hemabo n&#x27;est tenue de remplacer ou de r\u00e9parer les marchandises livr\u00e9es que si celles-ci ne sont pas conformes aux sp\u00e9cifications fournies par la partie adverse et mentionn\u00e9es dans le contrat. La partie adverse doit dans tous les cas en donner la possibilit\u00e9 \u00e0 Hemabo. Si la prestation convenue consistait (notamment) en la transformation de mat\u00e9riel fourni par la partie adverse, celle-ci doit alors fournir un nouveau mat\u00e9riel \u00e0 ses propres frais et \u00e0 ses propres risques. En cas de r\u00e9paration ou de remplacement, la partie adverse est tenue de retourner la marchandise \u00e0 Hemabo et d\u2019en transf\u00e9rer la propri\u00e9t\u00e9 \u00e0 Hemabo, sauf indication contraire de la part de Hemabo. Les retours doivent toujours \u00eatre effectu\u00e9s franco de port.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9.4<\/strong>&nbsp;En cas de non-conformit\u00e9, la partie adverse n&#x27;est pas habilit\u00e9e \u00e0 r\u00e9silier le contrat conclu avec Hemabo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9.5<\/strong>&nbsp;\u00c0 l&#x27;expiration d&#x27;un d\u00e9lai de garantie convenu par \u00e9crit, ou \u00e0 d\u00e9faut d&#x27;un tel d\u00e9lai, Hemabo est en droit de facturer \u00e0 la partie adverse l&#x27;ensemble des frais de r\u00e9paration ou de remplacement, y compris les frais administratifs, d&#x27;exp\u00e9dition et de d\u00e9placement, les frais de transport, les frais de d\u00e9placement et de s\u00e9jour ainsi que les heures de d\u00e9placement, \u00e0 la partie adverse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9.6<\/strong>&nbsp;Toute garantie sera annul\u00e9e si un d\u00e9faut r\u00e9sulte d&#x27;une utilisation incorrecte ou inappropri\u00e9e d&#x27;un bien livr\u00e9 par Hemabo, d&#x27;un stockage ou d&#x27;un entretien inad\u00e9quat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9.7<\/strong>&nbsp;La partie adverse est tenue d&#x27;inspecter (ou de faire inspecter) les marchandises livr\u00e9es d\u00e8s leur remise ou d\u00e8s que les travaux concern\u00e9s ont \u00e9t\u00e9 ex\u00e9cut\u00e9s par Hemabo. La partie adverse est tenue de v\u00e9rifier sans d\u00e9lai si la qualit\u00e9 et\/ou la quantit\u00e9 des produits livr\u00e9s correspondent \u00e0 ce qui a \u00e9t\u00e9 convenu avec Hemabo. Les d\u00e9fauts apparents doivent \u00eatre signal\u00e9s par \u00e9crit \u00e0 Hemabo dans les 5 jours calendaires suivant la livraison. Les d\u00e9fauts cach\u00e9s doivent \u00eatre signal\u00e9s par \u00e9crit \u00e0 Hemabo imm\u00e9diatement, et en tout \u00e9tat de cause au plus tard dans les 5 jours calendaires suivant leur d\u00e9couverte. La notification doit contenir une description aussi d\u00e9taill\u00e9e que possible du d\u00e9faut, afin que Hemabo soit en mesure d&#x27;y r\u00e9pondre de mani\u00e8re ad\u00e9quate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9.8<\/strong>&nbsp;Aucune r\u00e9clamation, quelle qu'en soit la nature, ne suspend l'obligation de paiement de la partie adverse. La partie adverse reste tenue de son obligation de prendre livraison et de payer les biens autrement command\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9.9<\/strong>&nbsp;Il n&#x27;est plus possible de faire valoir une r\u00e9clamation d\u00e8s lors que les articles ont \u00e9t\u00e9 trait\u00e9s, ou qu&#x27;ils ont \u00e9t\u00e9 trait\u00e9s ou manipul\u00e9s de mani\u00e8re inappropri\u00e9e, cela \u00e9tant laiss\u00e9 \u00e0 la seule appr\u00e9ciation de Hemabo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9.10<\/strong>&nbsp;Par d\u00e9rogation aux d\u00e9lais de prescription l\u00e9gaux, le d\u00e9lai de prescription de toutes les cr\u00e9ances \u00e0 l&#x27;encontre de Hemabo et des tiers auxquels Hemabo fait appel dans le cadre de l&#x27;ex\u00e9cution d&#x27;un contrat est d&#x27;un an. Si, pour quelque raison que ce soit, le d\u00e9lai de r\u00e9clamation pr\u00e9vu au paragraphe 5 ne devait pas \u00eatre applicable, les d\u00e9lais de r\u00e9clamation l\u00e9gaux, tels qu&#x27;ils d\u00e9coulent notamment de l&#x27;article 6:89 du Code civil n\u00e9erlandais et de l\u2019article 7:23 du Code civil n\u00e9erlandais sont r\u00e9duits \u00e0 trois mois \u00e0 compter de la date \u00e0 laquelle la partie adverse a d\u00e9couvert le d\u00e9faut ou aurait d\u00fb raisonnablement le d\u00e9couvrir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Article 10 \u2013 Limitation de responsabilit\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10.1<\/strong>&nbsp;Les r\u00e9clamations ne sont accept\u00e9es par Hemabo que si elles lui sont soumises dans les d\u00e9lais pr\u00e9vus \u00e0 l&#x27;article 9. Si, au moment de la r\u00e9clamation, la partie adverse est (encore) en d\u00e9faut, de quelque mani\u00e8re que ce soit, dans l&#x27;ex\u00e9cution de ses obligations, tout droit \u00e0 r\u00e9clamation est caduc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10.2<\/strong>&nbsp;\u00c0 l&#x27;expiration des d\u00e9lais susmentionn\u00e9s, la livraison est r\u00e9put\u00e9e accept\u00e9e de mani\u00e8re irr\u00e9vocable et inconditionnelle par la partie adverse. Il incombe \u00e0 la partie adverse d&#x27;apporter la preuve que la r\u00e9clamation a \u00e9t\u00e9 formul\u00e9e dans les d\u00e9lais. La partie adverse ne pourra prouver le bien-fond\u00e9 de sa r\u00e9clamation qu\u2019en se fondant sur les marchandises elles-m\u00eames, tandis qu&#x27;il lui incombe en outre de prouver que ces marchandises sont bien celles qui ont \u00e9t\u00e9 livr\u00e9es par Hemabo et qu&#x27;elles se trouvent dans le m\u00eame \u00e9tat qu&#x27;au moment o\u00f9 elles ont quitt\u00e9 l&#x27;entrep\u00f4t de Hemabo ou l&#x27;entrep\u00f4t ou l&#x27;usine d&#x27;un tiers. Seules les marchandises retourn\u00e9es \u00e0 la demande de Hemabo et dont la r\u00e9clamation a en outre \u00e9t\u00e9 accept\u00e9e par Hemabo seront accept\u00e9es par Hemabo. Les marchandises retourn\u00e9es \u00e0 tort restent \u00e0 la disposition de la partie adverse pendant une p\u00e9riode maximale de 10 jours ouvrables. Les frais de stockage et les risques restent \u00e0 la charge de la partie adverse. Pass\u00e9 ce d\u00e9lai, les marchandises sont renvoy\u00e9es \u00e0 la partie adverse. Les frais et les risques li\u00e9s au renvoi sont \u00e0 la charge de la partie adverse. En cas de r\u00e9clamation prouv\u00e9e par la partie adverse et jug\u00e9e fond\u00e9e par Hemabo, Hemabo peut, \u00e0 sa discr\u00e9tion, remplacer les pi\u00e8ces ou la marchandise faisant l\u2019objet de la r\u00e9clamation ou cr\u00e9diter la partie adverse, \u00e0 l\u2019exclusion de tout autre droit de la partie adverse \u00e0 des dommages-int\u00e9r\u00eats.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10.3<\/strong>&nbsp;Hemabo n&#x27;est en aucun cas tenue, y compris en cas, par exemple, de force majeure, de r\u00e9clamations, de manquement \u00e0 une obligation, de fait illicite, de conseil erron\u00e9, etc., de verser une quelconque indemnit\u00e9 et\/ou p\u00e9nalit\u00e9, de quelque nature que ce soit et pour quelque motif que ce soit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10.4<\/strong>&nbsp;Dans la mesure o\u00f9 il est l\u00e9galement \u00e9tabli que l'exclusion compl\u00e8te de responsabilit\u00e9 susmentionn\u00e9e (alin\u00e9a 2) ne peut \u00eatre maintenue, il est entendu que :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 que le montant des dommages-int\u00e9r\u00eats et de l&#x27;amende \u00e0 payer par Hemabo ne saurait en aucun cas d\u00e9passer le montant pour lequel l&#x27;assurance responsabilit\u00e9 civile souscrite par Hemabo donne droit \u00e0 une indemnisation, \u00e9tant entendu en outre que :<br>\u2013 le montant des dommages-int\u00e9r\u00eats et de l&#x27;amende \u00e0 verser par Hemabo \/ l&#x27;assureur ne peut en aucun cas d\u00e9passer le montant indiqu\u00e9 sur la facture relative au(x) cas concern\u00e9(s), et ce, m\u00eame dans le cas o\u00f9 la partie adverse ne pourrait pr\u00e9tendre \u00e0 aucune indemnisation de la part de l\u2019assureur de responsabilit\u00e9 civile de Hemabo, \u00e9tant entendu que :<br>\u2013 Hemabo ne sera responsable, au plus et exclusivement, qu\u2019\u00e0 concurrence d\u2019un montant maximal de 10 000 \u20ac au total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10.5<\/strong>&nbsp;Dans tous les cas, toutefois, Hemabo ne saurait en aucun cas \u00eatre tenue responsable des dommages indirects, cons\u00e9cutifs, immat\u00e9riels, des pertes d&#x27;exploitation, des dommages environnementaux, la location ou l\u2019achat d\u2019un bien de remplacement, les dommages li\u00e9s \u00e0 un manque \u00e0 gagner et\/ou \u00e0 une perte de chiffre d\u2019affaires, ou encore les dommages r\u00e9sultant de la responsabilit\u00e9 envers des tiers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10.6<\/strong>&nbsp;Si Hemabo a command\u00e9 aupr\u00e8s d\u2019un ou plusieurs tiers certaines mati\u00e8res premi\u00e8res destin\u00e9es \u00e0 ses produits et qu\u2019un ou plusieurs de ces tiers ont livr\u00e9 \u00e0 Hemabo des mati\u00e8res premi\u00e8res qui s\u2019\u00e9cartent, sur un ou plusieurs points, de ce que Hemabo avait command\u00e9, Hemabo ne saurait en aucun cas \u00eatre tenue responsable des dommages subis par la partie adverse du fait de l&#x27;utilisation de ces mati\u00e8res premi\u00e8res dans ses produits et\/ou en cons\u00e9quence de celle-ci.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10.7<\/strong>&nbsp;Hemabo ne saurait \u00eatre tenu responsable des \u00e9carts de dimensions des produits livr\u00e9s si celles-ci ne correspondent pas aux dimensions indiqu\u00e9es par le cocontractant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10.8<\/strong>&nbsp;Hemabo d\u00e9cline toute responsabilit\u00e9 en cas de diff\u00e9rences de couleur sur les articles command\u00e9s et\/ou command\u00e9s \u00e0 nouveau.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10.9<\/strong>&nbsp;Hemabo ne peut \u00eatre tenue responsable des dommages caus\u00e9s aux biens de la partie adverse, sauf si ceux-ci r\u00e9sultent d&#x27;une faute intentionnelle ou d&#x27;une n\u00e9gligence grave de la part de Hemabo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Article 11 \u2013 Clause de non-responsabilit\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>11.1<\/strong>&nbsp;La partie adverse garantit Hemabo contre toute r\u00e9clamation \u00e9ventuelle de tiers qui subiraient un pr\u00e9judice li\u00e9 \u00e0 l&#x27;ex\u00e9cution du contrat et dont la cause serait imputable \u00e0 une partie autre que Hemabo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>11.2<\/strong>&nbsp;Si Hemabo venait \u00e0 \u00eatre poursuivie par des tiers \u00e0 ce titre, la partie adverse serait tenue d&#x27;assister Hemabo tant \u00e0 l&#x27;amiable qu&#x27;en justice et de prendre sans d\u00e9lai toutes les mesures que l&#x27;on peut raisonnablement attendre d&#x27;elle dans ce cas. Si la partie adverse venait \u00e0 manquer \u00e0 son obligation de prendre les mesures ad\u00e9quates, Hemabo serait alors en droit, sans mise en demeure pr\u00e9alable, de prendre elle-m\u00eame ces mesures. Tous les frais et pr\u00e9judices subis par Hemabo et des tiers du fait de cette situation sont int\u00e9gralement \u00e0 la charge et aux risques de la partie adverse.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Article 12 \u2013 Droit applicable, r\u00e9clamations et litiges<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>12.1<\/strong>&nbsp;Toutes les relations juridiques entre Hemabo et son cocontractant sont r\u00e9gies exclusivement par le droit n\u00e9erlandais, m\u00eame si une obligation est ex\u00e9cut\u00e9e en tout ou en partie \u00e0 l&#x27;\u00e9tranger ou si la partie concern\u00e9e par la relation juridique y a son domicile. L&#x27;applicabilit\u00e9 de la Convention de Vienne sur les contrats de vente est exclue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>12.2<\/strong>&nbsp;Le tribunal du lieu d&#x27;\u00e9tablissement de Hemabo est seul comp\u00e9tent pour conna\u00eetre des litiges, sauf disposition contraire imp\u00e9rative de la loi. Hemabo est toujours en droit de porter le litige devant le tribunal comp\u00e9tent en vertu de la loi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Gestion de version : version 1 \u2013 20240418<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Artikel 1 \u2013 Toepasselijkheid 1.1&nbsp;De onderstaande voorwaarden zijn altijd van toepassing op alle rechtsverhoudingen uit hoofde waarvan Hemabo Kunststoftechniek B.V. (hierna: \u201cHemabo\u201d) werkzaamheden verricht en\/of goederen levert. De algemene voorwaarden maken in ieder geval deel uit van alle overeenkomsten waarbij Hemabo partij is en zijn voorts van toepassing tijdens onderhandelingen (de precontractuele fase), waarbij Hemabo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-14981","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Algemene verkoop- en leveringsvoorwaarden Hemabo Kunststoftechniek B.V. - Hemabo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hemabo.nl\/fr\/conditions-generales-de-vente-et-de-livraison-de-hemabo-kunststoftechniek-b-v\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Algemene verkoop- en leveringsvoorwaarden Hemabo Kunststoftechniek B.V. - Hemabo\" \/>\n<meta property=\"og:description\" content=\"Artikel 1 \u2013 Toepasselijkheid 1.1&nbsp;De onderstaande voorwaarden zijn altijd van toepassing op alle rechtsverhoudingen uit hoofde waarvan Hemabo Kunststoftechniek B.V. (hierna: \u201cHemabo\u201d) werkzaamheden verricht en\/of goederen levert. De algemene voorwaarden maken in ieder geval deel uit van alle overeenkomsten waarbij Hemabo partij is en zijn voorts van toepassing tijdens onderhandelingen (de precontractuele fase), waarbij Hemabo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hemabo.nl\/fr\/conditions-generales-de-vente-et-de-livraison-de-hemabo-kunststoftechniek-b-v\/\" \/>\n<meta property=\"og:site_name\" content=\"Hemabo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-22T13:30:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"26 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hemabo.nl\\\/en\\\/algemene-verkoop-en-leveringsvoorwaardenvan-hemabo-kunststoftechniek-b-v\\\/\",\"url\":\"https:\\\/\\\/hemabo.nl\\\/en\\\/algemene-verkoop-en-leveringsvoorwaardenvan-hemabo-kunststoftechniek-b-v\\\/\",\"name\":\"Algemene verkoop- en leveringsvoorwaarden Hemabo Kunststoftechniek B.V. - Hemabo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hemabo.nl\\\/#website\"},\"datePublished\":\"2026-07-22T13:20:49+00:00\",\"dateModified\":\"2026-07-22T13:30:27+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hemabo.nl\\\/en\\\/algemene-verkoop-en-leveringsvoorwaardenvan-hemabo-kunststoftechniek-b-v\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hemabo.nl\\\/#website\",\"url\":\"https:\\\/\\\/hemabo.nl\\\/\",\"name\":\"Hemabo\",\"description\":\"Precisie Kunststoftechniek\",\"publisher\":{\"@id\":\"https:\\\/\\\/hemabo.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hemabo.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hemabo.nl\\\/#organization\",\"name\":\"Hemabo\",\"url\":\"https:\\\/\\\/hemabo.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hemabo.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hemabo.nl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/hemabo-logo.svg\",\"contentUrl\":\"https:\\\/\\\/hemabo.nl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/hemabo-logo.svg\",\"width\":200,\"height\":51,\"caption\":\"Hemabo\"},\"image\":{\"@id\":\"https:\\\/\\\/hemabo.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conditions g\u00e9n\u00e9rales de vente et de livraison de Hemabo Kunststoftechniek B.V. - Hemabo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hemabo.nl\/fr\/conditions-generales-de-vente-et-de-livraison-de-hemabo-kunststoftechniek-b-v\/","og_locale":"fr_FR","og_type":"article","og_title":"Algemene verkoop- en leveringsvoorwaarden Hemabo Kunststoftechniek B.V. - Hemabo","og_description":"Artikel 1 \u2013 Toepasselijkheid 1.1&nbsp;De onderstaande voorwaarden zijn altijd van toepassing op alle rechtsverhoudingen uit hoofde waarvan Hemabo Kunststoftechniek B.V. (hierna: \u201cHemabo\u201d) werkzaamheden verricht en\/of goederen levert. De algemene voorwaarden maken in ieder geval deel uit van alle overeenkomsten waarbij Hemabo partij is en zijn voorts van toepassing tijdens onderhandelingen (de precontractuele fase), waarbij Hemabo [&hellip;]","og_url":"https:\/\/hemabo.nl\/fr\/conditions-generales-de-vente-et-de-livraison-de-hemabo-kunststoftechniek-b-v\/","og_site_name":"Hemabo","article_modified_time":"2026-07-22T13:30:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"26 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hemabo.nl\/en\/algemene-verkoop-en-leveringsvoorwaardenvan-hemabo-kunststoftechniek-b-v\/","url":"https:\/\/hemabo.nl\/en\/algemene-verkoop-en-leveringsvoorwaardenvan-hemabo-kunststoftechniek-b-v\/","name":"Conditions g\u00e9n\u00e9rales de vente et de livraison de Hemabo Kunststoftechniek B.V. - Hemabo","isPartOf":{"@id":"https:\/\/hemabo.nl\/#website"},"datePublished":"2026-07-22T13:20:49+00:00","dateModified":"2026-07-22T13:30:27+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hemabo.nl\/en\/algemene-verkoop-en-leveringsvoorwaardenvan-hemabo-kunststoftechniek-b-v\/"]}]},{"@type":"WebSite","@id":"https:\/\/hemabo.nl\/#website","url":"https:\/\/hemabo.nl\/","name":"H\u00e9mabo","description":"Pr\u00e9cision en Technologie des Mati\u00e8res Plastiques","publisher":{"@id":"https:\/\/hemabo.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hemabo.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hemabo.nl\/#organization","name":"H\u00e9mabo","url":"https:\/\/hemabo.nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hemabo.nl\/#\/schema\/logo\/image\/","url":"https:\/\/hemabo.nl\/wp-content\/uploads\/2025\/03\/hemabo-logo.svg","contentUrl":"https:\/\/hemabo.nl\/wp-content\/uploads\/2025\/03\/hemabo-logo.svg","width":200,"height":51,"caption":"Hemabo"},"image":{"@id":"https:\/\/hemabo.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hemabo.nl\/fr\/wp-json\/wp\/v2\/pages\/14981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hemabo.nl\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hemabo.nl\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hemabo.nl\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hemabo.nl\/fr\/wp-json\/wp\/v2\/comments?post=14981"}],"version-history":[{"count":2,"href":"https:\/\/hemabo.nl\/fr\/wp-json\/wp\/v2\/pages\/14981\/revisions"}],"predecessor-version":[{"id":14987,"href":"https:\/\/hemabo.nl\/fr\/wp-json\/wp\/v2\/pages\/14981\/revisions\/14987"}],"wp:attachment":[{"href":"https:\/\/hemabo.nl\/fr\/wp-json\/wp\/v2\/media?parent=14981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}